{"id":1068,"date":"2015-06-24T23:12:58","date_gmt":"2015-06-24T23:12:58","guid":{"rendered":"\/stories\/mexico-a-traves-de-la-cerveza\/"},"modified":"2015-06-24T23:12:58","modified_gmt":"2015-06-24T23:12:58","slug":"mexico-a-traves-de-la-cerveza","status":"publish","type":"post","link":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/","title":{"rendered":"M\u00e9xico a trav\u00e9s de la cerveza"},"content":{"rendered":"<p>Cuando est\u00e1s fuera de M\u00e9xico, no es raro encontrar quien te invite una Corona al enterarse que eres mexicano. Las cervezas mexicanas son reconocidas en todo el mundo y no por nada M\u00e9xico es el mayor exportador de esta bebida a nivel mundial. Pero viviendo en M\u00e9xico deja de causarnos emoci\u00f3n encontrar esas cervezas que se consiguen pr\u00e1cticamente en cada esquina. Entonces, \u00bfqu\u00e9 tal viajar un poco para probar algunas cervezas diferentes? No se trata de dejar de beber las que habitualmente bebemos, sino para conocer nuevas opciones con aromas y sabores muy diversos. Nunca sabes si encontrar\u00e1s una nueva favorita, o varias.<\/p>\n<figure id=\"attachment_13168\" aria-describedby=\"caption-attachment-13168\" style=\"width: 285px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13168\" src=\"\/stories\/wp-content\/uploads\/2021\/11\/Mapa.jpg\" alt=\"Baja California Norte, M\u00e9xico\" width=\"285\" height=\"172\" \/><figcaption id=\"caption-attachment-13168\" class=\"wp-caption-text\">Baja California Norte, M\u00e9xico<\/figcaption><\/figure>\n<p>El primer lugar que debes tener en mente para buscar nuevas cervezas es <a href=\"http:\/\/www.expedia.mx\/Destinos-En-Baja-California-Norte.d11115.Guia-de-Vuelos-Destinos\">Baja California.<\/a> El tri\u00e1ngulo formado entre Tijuana, Ensenada y Mexicali alberga algunos de los proyectos m\u00e1s innovadores de todo el pa\u00eds. Esto se debe a su cercan\u00eda con San Diego, ciudad conocida como la capital cervecera del mundo.<\/p>\n<p>Debes estar preparado para aromas y sabores que probablemente no has encontrado antes en tus cervezas. Los cerveceros \u2018artesanales\u2019 usan una mayor cantidad de ingredientes como los cereales malteados y el l\u00fapulo,\u00a0una flor que brinda aromas y amargor, pues justamente buscan ofrecer cervezas m\u00e1s interesantes para los consumidores.<\/p>\n<figure id=\"attachment_13177\" aria-describedby=\"caption-attachment-13177\" style=\"width: 2000px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13177 size-full\" src=\"\/stories\/wp-content\/uploads\/2021\/11\/Barril.jpg\" alt=\"Barril\" width=\"2000\" height=\"1333\" \/><figcaption id=\"caption-attachment-13177\" class=\"wp-caption-text\">Cerveza Artesanal Foto: StockSnap by Jeremy Ricketts<\/figcaption><\/figure>\n<p>En Tijuana puedes visitar cervecer\u00edas como Insurgente, Border Psycho o L\u00fadica, en Ensenada busca <a href=\"http:\/\/wendlandt.com.mx\/\">Wendlandt<\/a> o Agua Mala y en Mexicali ve a Fauna, Legi\u00f3n o Puerco Salvaje. Si tienes poco tiempo o no te gusta moverte tanto dentro de una misma ciudad, ve a alg\u00fan bar especializado en cerveza. En Tijuana est\u00e1 BCB Tasting Room y La Nacional, en Ensenada Wendlandt tiene su propio bar donde sirve algunas otras cervezas locales y en Mexicali quiz\u00e1s tu mejor opci\u00f3n sea El Sume.<\/p>\n<figure id=\"attachment_13174\" aria-describedby=\"caption-attachment-13174\" style=\"width: 3264px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13174\" src=\"\/stories\/wp-content\/uploads\/2021\/11\/2015-03-20-13.03.40-scaled.jpg\" alt=\"Cerveza artesanal Foto: StockSnap by Jeremy Ricketts\" width=\"3264\" height=\"2448\" \/><figcaption id=\"caption-attachment-13174\" class=\"wp-caption-text\">Wendlandt Cervecer\u00eda. Foto: Guillermo Ysusi.<\/figcaption><\/figure>\n<p>En otras ciudades de M\u00e9xico cada vez es m\u00e1s sencillo conseguir mayor diversidad de estilos de cervezas. Guadalajara es ejemplo de ello. La cervecer\u00eda Minerva fue uno de los pioneros en este tema hace m\u00e1s de 10 a\u00f1os y a partir de entonces m\u00e1s y m\u00e1s peque\u00f1as cervecer\u00edas han ido desarrollando sus productos.<\/p>\n<p>Si visitas <a href=\"http:\/\/www.expedia.mx\/Guadalajara.d1295.Guia-de-vacaciones\">Guadalajara<\/a>, no dejes de ir a El Dep\u00f3sito, uno de los primeros bares especializados en cerveza promovido por Minerva. Busca tambi\u00e9n otras marcas locales como Lola, quienes hacen una cerveza con palanqueta de cacahuate y otra con horchata, o Cervecer\u00eda de Colima, que no es de Guadalajara pero s\u00ed del estado vecino.<\/p>\n<figure id=\"attachment_13175\" aria-describedby=\"caption-attachment-13175\" style=\"width: 2448px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13175\" src=\"\/stories\/wp-content\/uploads\/2021\/11\/2015-03-20-21.28.09.jpg\" alt=\"Cerveza artesanal. Foto Guillermo Y\" width=\"2448\" height=\"2448\" \/><figcaption id=\"caption-attachment-13175\" class=\"wp-caption-text\">Cerveza artesanal. Foto Guillermo Ysusi<\/figcaption><\/figure>\n<p>La <a href=\"http:\/\/www.expedia.mx\/Ciudad-De-Mexico.d178285.Guia-de-vacaciones\">Ciudad de M\u00e9xico<\/a> no es la excepci\u00f3n. Hay muchos cerveceros caseros y algunas marcas un poco m\u00e1s grandes haciendo su esfuerzo por ofrecernos cervezas distintas. La \u00fanica cervecer\u00eda con una sala de degustaci\u00f3n, o algo parecido, es Ocozol, quienes sirven sus cervezas en un peque\u00f1o bar llamado De Garage. Para probar lo que hacen cervecer\u00edas como Flaco Cara de Perro, Indecorosa, La Chingoner\u00eda, as\u00ed como muchas otras, visita uno de estos bares: Hilaria, El Dep\u00f3sito (s\u00ed, tambi\u00e9n tiene 5 sucursales en el DF) o El Trappist, por mencionar s\u00f3lo algunos.<\/p>\n<p>Si ya recorriste algunos de estos lugares, no te desanimes, pues en todo estado del pa\u00eds hay cada vez m\u00e1s opciones por conocer. Esta es s\u00f3lo una probadita de las cervezas que se est\u00e1n haciendo en M\u00e9xico.<\/p>\n<p>Y t\u00fa, \u00bfCu\u00e1l ya probaste?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando est\u00e1s fuera de M\u00e9xico, no es raro encontrar quien te invite una Corona al enterarse que eres mexicano. Las cervezas mexicanas son reconocidas en todo el mundo y no por nada M\u00e9xico es el mayor exportador de esta bebida a nivel mundial. Pero viviendo en M\u00e9xico deja de causarnos emoci\u00f3n encontrar esas cervezas que&hellip; <a class=\"more-link\" href=\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\">Continue reading <span class=\"screen-reader-text\">M\u00e9xico a trav\u00e9s de la cerveza<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":1073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,6],"tags":[105,475,476,477,37,67,34,173,86,162],"authors":[],"class_list":["post-1068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia","category-interes","tag-baja-california","tag-cerveza-en-mexco","tag-cerveza-minerva","tag-ciudad-de-mpexico","tag-featured","tag-gastronomia","tag-mexico","tag-que-hacer","tag-vacaciones","tag-viaje","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico a trav\u00e9s de la cerveza | Expedia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico a trav\u00e9s de la cerveza | Expedia\" \/>\n<meta property=\"og:description\" content=\"Cuando est\u00e1s fuera de M\u00e9xico, no es raro encontrar quien te invite una Corona al enterarse que eres mexicano. Las cervezas mexicanas son reconocidas en todo el mundo y no por nada M\u00e9xico es el mayor exportador de esta bebida a nivel mundial. Pero viviendo en M\u00e9xico deja de causarnos emoci\u00f3n encontrar esas cervezas que&hellip; Continue reading M\u00e9xico a trav\u00e9s de la cerveza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia MX Stories\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-24T23:12:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\",\"url\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\",\"name\":\"M\u00e9xico a trav\u00e9s de la cerveza | Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.mx\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg\",\"datePublished\":\"2015-06-24T23:12:58+00:00\",\"dateModified\":\"2015-06-24T23:12:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/263d827ac415645fdb446addb27341c6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage\",\"url\":\"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg\",\"contentUrl\":\"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg\",\"width\":2560,\"height\":1840,\"caption\":\"M\u00e9xico a trav\u00e9s de la cerveza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.mx\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inter\u00e9s\",\"item\":\"https:\/\/www.expedia.mx\/stories\/interes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gastronom\u00eda\",\"item\":\"https:\/\/www.expedia.mx\/stories\/interes\/gastronomia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00e9xico a trav\u00e9s de la cerveza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/#website\",\"url\":\"https:\/\/www.expedia.mx\/stories\/\",\"name\":\"Expedia MX Stories\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.mx\/stories\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/263d827ac415645fdb446addb27341c6\",\"name\":\"agray\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/54a90d654f4df3e074299cf837ff9936d06299866d2b347a1613926ce373496c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/54a90d654f4df3e074299cf837ff9936d06299866d2b347a1613926ce373496c?s=96&d=mm&r=g\",\"caption\":\"agray\"},\"url\":\"https:\/\/www.expedia.mx\/stories\/author\/agray\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico a trav\u00e9s de la cerveza | Expedia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e9xico a trav\u00e9s de la cerveza | Expedia","og_description":"Cuando est\u00e1s fuera de M\u00e9xico, no es raro encontrar quien te invite una Corona al enterarse que eres mexicano. Las cervezas mexicanas son reconocidas en todo el mundo y no por nada M\u00e9xico es el mayor exportador de esta bebida a nivel mundial. Pero viviendo en M\u00e9xico deja de causarnos emoci\u00f3n encontrar esas cervezas que&hellip; Continue reading M\u00e9xico a trav\u00e9s de la cerveza","og_url":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/","og_site_name":"Expedia MX Stories","article_published_time":"2015-06-24T23:12:58+00:00","og_image":[{"width":2560,"height":1840,"url":"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg","type":"image\/jpeg"}],"author":"agray","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agray","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/","url":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/","name":"M\u00e9xico a trav\u00e9s de la cerveza | Expedia","isPartOf":{"@id":"https:\/\/www.expedia.mx\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg","datePublished":"2015-06-24T23:12:58+00:00","dateModified":"2015-06-24T23:12:58+00:00","author":{"@id":"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/263d827ac415645fdb446addb27341c6"},"breadcrumb":{"@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#primaryimage","url":"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg","contentUrl":"https:\/\/www.expedia.mx\/stories\/wp-content\/uploads\/2021\/11\/Foto-Cerveza-scaled.jpg","width":2560,"height":1840,"caption":"M\u00e9xico a trav\u00e9s de la cerveza"},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.mx\/stories\/mexico-a-traves-de-la-cerveza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.mx\/stories\/"},{"@type":"ListItem","position":2,"name":"Inter\u00e9s","item":"https:\/\/www.expedia.mx\/stories\/interes\/"},{"@type":"ListItem","position":3,"name":"Gastronom\u00eda","item":"https:\/\/www.expedia.mx\/stories\/interes\/gastronomia\/"},{"@type":"ListItem","position":4,"name":"M\u00e9xico a trav\u00e9s de la cerveza"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.mx\/stories\/#website","url":"https:\/\/www.expedia.mx\/stories\/","name":"Expedia MX Stories","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.mx\/stories\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/263d827ac415645fdb446addb27341c6","name":"agray","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.mx\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/54a90d654f4df3e074299cf837ff9936d06299866d2b347a1613926ce373496c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54a90d654f4df3e074299cf837ff9936d06299866d2b347a1613926ce373496c?s=96&d=mm&r=g","caption":"agray"},"url":"https:\/\/www.expedia.mx\/stories\/author\/agray\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/posts\/1068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/comments?post=1068"}],"version-history":[{"count":0,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/posts\/1068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/media\/1073"}],"wp:attachment":[{"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/media?parent=1068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/categories?post=1068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/tags?post=1068"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.mx\/stories\/wp-json\/wp\/v2\/authors?post=1068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}